{"id":15748,"date":"2021-10-13T09:47:54","date_gmt":"2021-10-13T07:47:54","guid":{"rendered":"https:\/\/www.airwell.com\/soluzioni-efficienti-dal-punto-di-vista-energetico\/"},"modified":"2021-10-18T18:13:08","modified_gmt":"2021-10-18T16:13:08","slug":"efficienza-energetica","status":"publish","type":"page","link":"https:\/\/www.airwell.com\/it\/efficienza-energetica\/","title":{"rendered":"Soluzioni ad alta efficienza energetica"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<style type=\"text\/css\">@media only screen and (min-width: 1300px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 500px; }  } @media only screen and (max-width: 1299px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 416.66666666667px; }  } @media only screen and (max-width: 1000px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 357.14285714286px; }  } @media only screen and (max-width: 690px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 185.18518518519px; }  } <\/style><div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"\" data-parallax=\"false\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"true\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"false\" data-height=\"500\" data-min-height=\"\" data-arrows=\"false\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.airwell.com\/wp-content\/uploads\/2021\/03\/eco_slide-scaled.jpg);\"> &nbsp; <\/div><\/div><div class=\"container\">\r\n\t\t\t\t\t\t<div class=\"content\"><h1>Soluzioni ad alta efficienza energetica<\/h1><p  ><span>Ridurre l'impatto ambientale dei nostri prodotti<br>\u00e8 una priorit\u00e0 per Airwell<\/span><\/p><\/div>\r\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50px&#8221; left_padding_desktop=&#8221;130px&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;130px&#8221; left_padding_tablet=&#8221;0px&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0px&#8221; left_padding_phone=&#8221;0px&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<h3 style=\"text-align: center;\">State cercando una soluzione di riscaldamento e raffreddamento efficiente ed ecologica? Passate alle pompe di calore Airwell e riducete subito i vostri consumi<\/h3>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;secteurs-section clear-order&#8221; id=&#8221;anchor-hotels&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;1458&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; bottom_margin=&#8221;20&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text el_class=&#8221;secteurs-section__title&#8221;]\n<h3>Le pompe di calore sono la soluzione all-in-one pi\u00f9 ecologica ed economica<\/h3>\n[\/vc_column_text][vc_raw_html el_class=&#8221;no-min-height&#8221;]PHNwYW4gY2xhc3M9ImRpdmlkZXIiPjwvc3Bhbj4=[\/vc_raw_html][vc_column_text el_class=&#8221;secteurs-section__text&#8221;]\n<p class=\"p1\">Per produrre calore, una pompa di calore prende circa il 70% del suo fabbisogno energetico dall&#8217;aria, che \u00e8 &#8220;gratuita&#8221;, il restante 30% \u00e8 il consumo elettrico del compressore.<\/p>\n<p>Rispettose dell&#8217;ambiente, le pompe di calore non emettono CO2 durante il funzionamento. Solo il refrigerante R32 contiene carbonio (da 3 a 4 volte meno dei refrigeranti tradizionali R410A) ma funziona in un ciclo chiuso e pu\u00f2 essere recuperato e riciclato alla fine della vita del prodotto.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_1=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;secteurs-section&#8221; id=&#8221;anchor-retail&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; bottom_margin=&#8221;20&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text el_class=&#8221;secteurs-section__title&#8221;]\n<h3>Vi state chiedendo se comprare una pompa di calore o un sistema di climatizzazione reversibile?<\/h3>\n[\/vc_column_text][vc_raw_html el_class=&#8221;no-min-height&#8221;]PHNwYW4gY2xhc3M9ImRpdmlkZXIiPjwvc3Bhbj4=[\/vc_raw_html][vc_column_text el_class=&#8221;secteurs-section__text&#8221;]\n<p>\u00c8 lo stesso! Un condizionatore d&#8217;aria reversibile \u00e8 una pompa di calore aria-aria, che pu\u00f2 produrre sia aria calda che fredda.<\/p>\n<p class=\"p1\">Le pompe di calore aria-acqua sono le pi\u00f9 adatte al riscaldamento a pavimento o ai radiatori ad acqua convenzionali; facili da installare e con un&#8217;alta efficienza energetica.<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;1459&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;secteurs-section clear-order&#8221; id=&#8221;anchor-hotels&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;1460&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; bottom_margin=&#8221;20&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text el_class=&#8221;secteurs-section__title&#8221;]\n<h3>Tagliate in modo significativo la vostra bolletta energetica.<\/h3>\n[\/vc_column_text][vc_raw_html el_class=&#8221;no-min-height&#8221;]PHNwYW4gY2xhc3M9ImRpdmlkZXIiPjwvc3Bhbj4=[\/vc_raw_html][vc_column_text el_class=&#8221;secteurs-section__text&#8221;]Una pompa di calore sfrutta un&#8217;energia gratuita e inesauribile: le calorie dell&#8217;aria.<\/p>\n<p>L&#8217;installazione di una pompa di calore pu\u00f2 ridurre la vostra bolletta energetica di un fattore 2 o 3 rispetto a un sistema di riscaldamento convenzionale (una verifica dell&#8217;isolamento della vostra casa sar\u00e0 necessaria in anticipo per identificare eventuali perdite di energia). L&#8217;accoppiamento di una pompa di calore con una caldaia a gas o a olio \u00e8 possibile.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;1456&#8243; bg_position=&#8221;center center&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;90&#8243; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;90&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;clear-order&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<h2 style=\"text-align: center;\"><span style=\"font-weight: bold; color: #ffffff;\">Buono per voi e per il pianeta<\/span><\/h2>\n[\/vc_column_text][vc_column_text el_class=&#8221;labels-text-fullw&#8221;]\n<h4 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Alla Airwell, tutti i nostri prodotti e le nostre soluzioni sono concepiti pensando all&#8217;eco-efficienza, dalla fase di progettazione fino all&#8217;uso quotidiano.<\/span><\/h4>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_1=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;secteurs-section clear-order&#8221; id=&#8221;anchor-bureaux&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; bottom_margin=&#8221;20&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text el_class=&#8221;secteurs-section__title&#8221;]\n<h3>Tecnologia inverter per il controllo della temperatura<\/h3>\n[\/vc_column_text][vc_raw_html el_class=&#8221;no-min-height&#8221;]PHNwYW4gY2xhc3M9ImRpdmlkZXIiPjwvc3Bhbj4=[\/vc_raw_html][vc_column_text el_class=&#8221;secteurs-section__text&#8221;]Tutte le pompe di calore Airwell sono fornite con tecnologia inverter. Questa tecnologia impedisce l&#8217;avvio e l&#8217;arresto dell&#8217;unit\u00e0 regolando la potenza del compressore.  Grazie a un inverter integrato, la pompa di calore adatta in modo intelligente la sua potenza in base alla temperatura esterna e alle esigenze della casa. Questo evita frequenti accensioni del riscaldamento e i picchi di consumo, ottimizzando cos\u00ec i costi.[\/vc_column_text][vc_raw_html]PGEgY2xhc3M9ImJ0bi1wcmltYXJ5IiBocmVmPSIjIj5WZWRpIGxlIG5vc3RyZSBwb21wZSBkaSBjYWxvcmU8L2E+[\/vc_raw_html][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;1461&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-15748","page","type-page","status-publish"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<link rel=\"canonical\" href=\"https:\/\/www.airwell.com\/it\/nectar_slider\/brouillon-auto-11\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Airwell - Soluzioni di aria condizionata e riscaldamento\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Brouillon auto - Airwell\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.airwell.com\/it\/nectar_slider\/brouillon-auto-11\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.airwell.com\/wp-content\/uploads\/2020\/11\/slider_video.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.airwell.com\/wp-content\/uploads\/2020\/11\/slider_video.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1474\" \/>\n\t\t<meta property=\"og:image:height\" content=\"819\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-10-14T13:19:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-10-18T16:14:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Brouillon auto - Airwell\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.airwell.com\/wp-content\/uploads\/2020\/11\/slider_video.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/nectar_slider\\\/brouillon-auto-11\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/efficienza-energetica\\\/#listItem\",\"name\":\"Soluzioni ad alta efficienza energetica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/efficienza-energetica\\\/#listItem\",\"position\":2,\"name\":\"Soluzioni ad alta efficienza energetica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/#listItem\",\"name\":\"Accueil\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/#organization\",\"name\":\"Airwell\",\"description\":\"Soluzioni di aria condizionata e riscaldamento\",\"url\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/\",\"telephone\":\"+33176218200\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.airwell.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo_Airwell.svg\",\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/nectar_slider\\\/brouillon-auto-11\\\/#organizationLogo\",\"width\":157,\"height\":37},\"image\":{\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/nectar_slider\\\/brouillon-auto-11\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKceazQwwi_h-1vHklDDtWg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/airwell\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/nectar_slider\\\/brouillon-auto-11\\\/#webpage\",\"url\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/nectar_slider\\\/brouillon-auto-11\\\/\",\"name\":\"Brouillon auto - Airwell\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/nectar_slider\\\/brouillon-auto-11\\\/#breadcrumblist\"},\"datePublished\":\"2021-10-14T15:19:04+02:00\",\"dateModified\":\"2021-10-18T18:14:52+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/\",\"name\":\"Airwell\",\"description\":\"Soluzioni di aria condizionata e riscaldamento\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.airwell.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Brouillon auto - Airwell","description":"","canonical_url":"https:\/\/www.airwell.com\/it\/nectar_slider\/brouillon-auto-11\/","robots":"","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.airwell.com\/it\/nectar_slider\/brouillon-auto-11\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.airwell.com\/it\/#listItem","position":1,"name":"Accueil","item":"https:\/\/www.airwell.com\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.airwell.com\/it\/efficienza-energetica\/#listItem","name":"Soluzioni ad alta efficienza energetica"}},{"@type":"ListItem","@id":"https:\/\/www.airwell.com\/it\/efficienza-energetica\/#listItem","position":2,"name":"Soluzioni ad alta efficienza energetica","previousItem":{"@type":"ListItem","@id":"https:\/\/www.airwell.com\/it\/#listItem","name":"Accueil"}}]},{"@type":"Organization","@id":"https:\/\/www.airwell.com\/it\/#organization","name":"Airwell","description":"Soluzioni di aria condizionata e riscaldamento","url":"https:\/\/www.airwell.com\/it\/","telephone":"+33176218200","logo":{"@type":"ImageObject","url":"https:\/\/www.airwell.com\/wp-content\/uploads\/2020\/11\/Logo_Airwell.svg","@id":"https:\/\/www.airwell.com\/it\/nectar_slider\/brouillon-auto-11\/#organizationLogo","width":157,"height":37},"image":{"@id":"https:\/\/www.airwell.com\/it\/nectar_slider\/brouillon-auto-11\/#organizationLogo"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCKceazQwwi_h-1vHklDDtWg","https:\/\/www.linkedin.com\/company\/airwell\/"]},{"@type":"WebPage","@id":"https:\/\/www.airwell.com\/it\/nectar_slider\/brouillon-auto-11\/#webpage","url":"https:\/\/www.airwell.com\/it\/nectar_slider\/brouillon-auto-11\/","name":"Brouillon auto - Airwell","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.airwell.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.airwell.com\/it\/nectar_slider\/brouillon-auto-11\/#breadcrumblist"},"datePublished":"2021-10-14T15:19:04+02:00","dateModified":"2021-10-18T18:14:52+02:00"},{"@type":"WebSite","@id":"https:\/\/www.airwell.com\/it\/#website","url":"https:\/\/www.airwell.com\/it\/","name":"Airwell","description":"Soluzioni di aria condizionata e riscaldamento","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.airwell.com\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Airwell - Soluzioni di aria condizionata e riscaldamento","og:type":"article","og:title":"Brouillon auto - Airwell","og:url":"https:\/\/www.airwell.com\/it\/nectar_slider\/brouillon-auto-11\/","og:image":"https:\/\/www.airwell.com\/wp-content\/uploads\/2020\/11\/slider_video.png","og:image:secure_url":"https:\/\/www.airwell.com\/wp-content\/uploads\/2020\/11\/slider_video.png","og:image:width":1474,"og:image:height":819,"article:published_time":"2021-10-14T13:19:04+00:00","article:modified_time":"2021-10-18T16:14:52+00:00","twitter:card":"summary","twitter:title":"Brouillon auto - Airwell","twitter:image":"https:\/\/www.airwell.com\/wp-content\/uploads\/2020\/11\/slider_video.png"},"aioseo_meta_data":{"post_id":"15748","title":null,"description":"State cercando una soluzione di riscaldamento e raffreddamento efficiente ed ecologica? Scoprite le pompe di calore Airwell per ridurre i vostri consumi.","keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":"#post_title #separator_sa #site_title","og_description":"State cercando una soluzione di riscaldamento e raffreddamento efficiente ed ecologica? Scoprite le pompe di calore Airwell per ridurre i vostri consumi.","og_object_type":"default","og_image_type":"custom_image","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":"https:\/\/www.airwell.com\/wp-content\/uploads\/2021\/03\/eco_slide-scaled.jpg","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"#aioseo-web-page-63f3300d5cf86","slug":"web-page","graphName":"WebPage","label":"Web Page","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-10-13 07:47:56","updated":"2025-06-04 14:35:35","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"featured_image_src":null,"_links":{"self":[{"href":"https:\/\/www.airwell.com\/it\/wp-json\/wp\/v2\/pages\/15748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.airwell.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.airwell.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.airwell.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.airwell.com\/it\/wp-json\/wp\/v2\/comments?post=15748"}],"version-history":[{"count":3,"href":"https:\/\/www.airwell.com\/it\/wp-json\/wp\/v2\/pages\/15748\/revisions"}],"predecessor-version":[{"id":16010,"href":"https:\/\/www.airwell.com\/it\/wp-json\/wp\/v2\/pages\/15748\/revisions\/16010"}],"wp:attachment":[{"href":"https:\/\/www.airwell.com\/it\/wp-json\/wp\/v2\/media?parent=15748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}