{"id":10,"name":"Ceren Aiydin","url":"","description":"","link":"https:\/\/www.airwell.com\/nl\/author\/lea\/","slug":"lea","meta":[],"_links":{"self":[{"href":"https:\/\/www.airwell.com\/nl\/wp-json\/wp\/v2\/users\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.airwell.com\/nl\/wp-json\/wp\/v2\/users"}]}}